{"id":943,"date":"2020-08-08T12:52:18","date_gmt":"2020-08-08T11:52:18","guid":{"rendered":"https:\/\/le12.ma\/fr\/?p=943"},"modified":"2020-08-08T12:52:18","modified_gmt":"2020-08-08T11:52:18","slug":"wac-ock-botola-pro-d1-pluies-dabsences-cote-wydadi","status":"publish","type":"post","link":"https:\/\/le12.ma\/fr\/wac-ock-botola-pro-d1-pluies-dabsences-cote-wydadi\/","title":{"rendered":"WAC-OCK (Botola Pro D1) : Pluies d\u2019absences c\u00f4t\u00e9 wydadi"},"content":{"rendered":"<p><span style=\"color: #ff0000;\"><strong>Le12sport\/Adil<\/strong><\/span><\/p>\n<p><strong>Pour la r\u00e9ception de l\u2019OCK lundi prochain pour le compte de la 21\u00e8me journ\u00e9e de la Botola Pro D1, le WAC sera priv\u00e9 de plusieurs de ses titulaires. Il s\u2019agit du d\u00e9fenseur Ivoirien Cheikh Ibrahim Comara, bless\u00e9 lors du revers face \u00e0 la RSB ou encore Yahya Jabrane, suspendu lors de la m\u00eame rencontre. Sans oublier Abdellatif Noussir qui souffre toujours de la cheville.<\/strong><br \/>\n<strong>Par contre, Juan Garrido aura la possibilit\u00e9 de titulariser Badie Aouk, absent cotre les co\u00e9quipiers de Zakaria Hadraf \u00e0 cause d\u2019un p\u00e9pin physique survenu avant le d\u00e9placement vers Berkane.<\/strong><br \/>\n<strong>Pour rappel, le WAC, malgr\u00e9 la d\u00e9faite \u00e0 Berkane (2-1), est toujours leader du championnat national avec 37 points.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le12sport\/Adil Pour la r\u00e9ception de l\u2019OCK lundi prochain pour le compte de la 21\u00e8me journ\u00e9e de la Botola Pro D1, le WAC sera priv\u00e9 de plusieurs de ses titulaires. Il s\u2019agit du d\u00e9fenseur Ivoirien Cheikh Ibrahim Comara, bless\u00e9 lors du revers face \u00e0 la RSB ou encore Yahya Jabrane, suspendu lors de la m\u00eame rencontre. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":944,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[27],"tags":[],"yst_prominent_words":[2543,2957],"jetpack_featured_media_url":"https:\/\/le12.ma\/fr\/wp-content\/uploads\/2020\/08\/COMARA-WAC.jpg","_links":{"self":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts\/943"}],"collection":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/comments?post=943"}],"version-history":[{"count":1,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts\/943\/revisions"}],"predecessor-version":[{"id":945,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts\/943\/revisions\/945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/media\/944"}],"wp:attachment":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/media?parent=943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/categories?post=943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/tags?post=943"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/yst_prominent_words?post=943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}