{"id":25035,"date":"2022-05-21T17:30:17","date_gmt":"2022-05-21T16:30:17","guid":{"rendered":"https:\/\/le12.ma\/fr\/?p=25035"},"modified":"2022-05-21T16:46:00","modified_gmt":"2022-05-21T15:46:00","slug":"bourse-de-casablanca-une-nouvelle-semaine-dans-le-rouge","status":"publish","type":"post","link":"https:\/\/le12.ma\/fr\/bourse-de-casablanca-une-nouvelle-semaine-dans-le-rouge\/","title":{"rendered":"Bourse de Casablanca : Une nouvelle semaine dans le rouge"},"content":{"rendered":"<h4><span style=\"color: #000000;\"><strong><a href=\"https:\/\/le12.ma\/fr\/la-bourse-de-casablanca-en-hausse-ce-jeudi\/\">La Bourse de Casablanca<\/a> s\u2019est inscrite sur une trajectoire baissi\u00e8re sur la p\u00e9riode allant du 16 au 20 mai courant, alignant ainsi une quatri\u00e8me semaine de <a href=\"https:\/\/www.insee.fr\/fr\/statistiques\/1893623?sommaire=1893627\">baisse cons\u00e9cutive<\/a>.<\/strong><\/span><\/h4>\n<p><strong>Au terme de cette semaine, le Masi, l\u2019indice global compos\u00e9 de toutes les valeurs de type action, s\u2019est repli\u00e9 de 0,44% \u00e0 12.626,59 points (pts), et le Morocco Stock Index 20 (MSI20), qui refl\u00e8te la performance des cours des 20 entreprises les plus liquides, a perdu 0,57% \u00e0 1.019,54 pts. Depuis le d\u00e9but de l\u2019ann\u00e9e, ces deux barom\u00e8tres affichent des baisses respectives de -5,48% et -6,1%.<\/strong><\/p>\n<p><strong>Le Casablanca ESG 10, indice de r\u00e9f\u00e9rence Environnement, Social et Gouvernance (ESG), a recul\u00e9 pour sa part de 0,23% \u00e0 946,05 points, ramenant ainsi sa contreperformance annuelle \u00e0 -5,21%.<\/strong><\/p>\n<p><strong>Sur le front des valeurs, 14 indices sectoriels ont cl\u00f4tur\u00e9 la semaine sur une note n\u00e9gative, contre 8 en hausse, tandis que celui des soci\u00e9t\u00e9s de portefeuilles-holdings est rest\u00e9 stable.<\/strong><\/p>\n<p><strong>Le secteur des assurances (-3,27%) a accus\u00e9 le plus fort repli de la p\u00e9riode, suivi par celui des ing\u00e9nieries et biens d\u2019\u00e9quipement industriels (-2,41%) et des services de transport (-2,2%).<\/strong><\/p>\n<p><strong>A la hausse, l\u2019indice sectoriel des mines (6,24%%) a enregistr\u00e9 la meilleure performance hebdomadaire, devan\u00e7ant l\u2019indice de l\u2019\u00e9lectricit\u00e9 (5,56%) et celui du p\u00e9trole et gaz (2,18%).<\/strong><\/p>\n<p><strong>Le volume global s\u2019est \u00e9lev\u00e9 \u00e0 plus de 544,976 millions de dirhams (MDH), r\u00e9alis\u00e9 majoritairement sur le march\u00e9 central actions et domin\u00e9 par les transactions portant sur Attijariwafa Bank (76,583 MDH), LafargeHolcim Maroc (44,477 MDH) et Sodep-Marsa Maroc (41,184 MDH).<\/strong><\/p>\n<p><strong>La capitalisation boursi\u00e8re a d\u00e9pass\u00e9, quant \u00e0 elle, les 659,577 milliards de dirhams (MMDH).<\/strong><\/p>\n<p><strong>Les plus fortes baisses de la semaine ont \u00e9t\u00e9 accus\u00e9es par R\u00e9alisations m\u00e9caniques (-8,9%), IB Maroc.com (-5,94%), Atlantasanad (-4,74%), Wafa Assurance (-4,35%) et Promopharm S.A (-3,97%).<\/strong><\/p>\n<p><strong>A l\u2019oppos\u00e9, les meilleures performances ont \u00e9t\u00e9 l\u2019\u0153uvre de SMI (23,18%), Mini\u00e8re Touissit (7,35%), Cartier Saada (5,71%), Taqa Morocco (5,56%) et Involys (4,37%).<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Bourse de Casablanca s\u2019est inscrite sur une trajectoire baissi\u00e8re sur la p\u00e9riode allant du 16 au 20 mai courant, alignant ainsi une quatri\u00e8me semaine de baisse cons\u00e9cutive. Au terme de cette semaine, le Masi, l\u2019indice global compos\u00e9 de toutes les valeurs de type action, s\u2019est repli\u00e9 de 0,44% \u00e0 12.626,59 points (pts), et le [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[26,25],"tags":[],"yst_prominent_words":[3830,80,1567,2658,3000,1225,2650,69,2810,2657,2403,1266,1352,3930,928,2648],"jetpack_featured_media_url":"https:\/\/le12.ma\/fr\/wp-content\/uploads\/2021\/06\/Bourse.jpg","_links":{"self":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts\/25035"}],"collection":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/comments?post=25035"}],"version-history":[{"count":2,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts\/25035\/revisions"}],"predecessor-version":[{"id":25037,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts\/25035\/revisions\/25037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/media\/18014"}],"wp:attachment":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/media?parent=25035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/categories?post=25035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/tags?post=25035"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/yst_prominent_words?post=25035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}