{"id":1993,"date":"2020-08-21T18:00:40","date_gmt":"2020-08-21T17:00:40","guid":{"rendered":"https:\/\/le12.ma\/fr\/?p=1993"},"modified":"2020-08-21T18:00:40","modified_gmt":"2020-08-21T17:00:40","slug":"finale-ligue-europa-un-arbitre-neerlandais-au-sifflet","status":"publish","type":"post","link":"https:\/\/le12.ma\/fr\/finale-ligue-europa-un-arbitre-neerlandais-au-sifflet\/","title":{"rendered":"Finale Ligue Europa : Un arbitre n\u00e9erlandais au sifflet"},"content":{"rendered":"<p><span style=\"color: #ff0000;\"><strong>Le12sport-M.manaf <\/strong><\/span><\/p>\n<p><strong>L\u2019UEFA a d\u00e9sign\u00e9 l&rsquo;arbitre qui officiera la finale de La Ligue Europe entre le FC S\u00e9ville et l\u2019Inter Milan, pr\u00e9vue vendredi \u00e0 Cologne en Allemagne. Il s&rsquo;agit du n\u00e9erlandais Danny Makkelie (37 ans). Pour l&rsquo;arbitre batave, ce sera une grande premi\u00e8re, puisqu&rsquo;il n&rsquo;a jamais offici\u00e9 lors d&rsquo;une finale de comp\u00e9tition europ\u00e9enne.<\/strong><br \/>\n<strong>Cette saison, il a notamment arbitr\u00e9 7 rencontres de Ligue des Champions et une en Ligue Europa entre le Bayer Leverkusen et les Rangers. Le natif de Willemstad sera assist\u00e9 par ses compatriotes Mario Diks et Hessel Steegstra, le Grec Anastasios Sidiropolous est le quatri\u00e8me arbitre. Le N\u00e9erlandais Jochem Kamphuis est l\u2019arbitre vid\u00e9o assist\u00e9 par son compatriote Kevin Blom et les Polonais Tomasz Sokolnicki et Pawel Gil.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le12sport-M.manaf L\u2019UEFA a d\u00e9sign\u00e9 l&rsquo;arbitre qui officiera la finale de La Ligue Europe entre le FC S\u00e9ville et l\u2019Inter Milan, pr\u00e9vue vendredi \u00e0 Cologne en Allemagne. Il s&rsquo;agit du n\u00e9erlandais Danny Makkelie (37 ans). Pour l&rsquo;arbitre batave, ce sera une grande premi\u00e8re, puisqu&rsquo;il n&rsquo;a jamais offici\u00e9 lors d&rsquo;une finale de comp\u00e9tition europ\u00e9enne. Cette saison, il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1994,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[26,27],"tags":[],"yst_prominent_words":[6046,1071,6044,278,6043],"jetpack_featured_media_url":"https:\/\/le12.ma\/fr\/wp-content\/uploads\/2020\/08\/Danny-Makkelie-arbitre.jpg","_links":{"self":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts\/1993"}],"collection":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/comments?post=1993"}],"version-history":[{"count":1,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts\/1993\/revisions"}],"predecessor-version":[{"id":1995,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts\/1993\/revisions\/1995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/media\/1994"}],"wp:attachment":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/media?parent=1993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/categories?post=1993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/tags?post=1993"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/yst_prominent_words?post=1993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}