{"id":1135,"date":"2020-08-10T19:08:53","date_gmt":"2020-08-10T18:08:53","guid":{"rendered":"https:\/\/le12.ma\/fr\/?p=1135"},"modified":"2020-08-10T19:08:53","modified_gmt":"2020-08-10T18:08:53","slug":"atletico-leipzig-match-toujours-programme","status":"publish","type":"post","link":"https:\/\/le12.ma\/fr\/atletico-leipzig-match-toujours-programme\/","title":{"rendered":"ATL\u00c9TICO-LEIPZIG: MATCH TOUJOURS PROGRAMM\u00c9"},"content":{"rendered":"<p><span style=\"color: #ff0000;\"><strong>Le12sport<\/strong><\/span><\/p>\n<p><strong>Le quart de finale de Ligue des champions entre Leipzig et l\u2019Atl\u00e9tico Madrid est \u201cprogramm\u00e9 comme pr\u00e9vu\u201d jeudi, a assur\u00e9 lundi l\u2019UEFA, au lendemain de l\u2019annonce de tests positifs au Covid-19 concernant deux membres du club espagnol.<\/strong><\/p>\n<p><strong>Le quart de finale entre Leipzig et l\u2019Atl\u00e9tico Madrid \u201cest programm\u00e9 comme pr\u00e9vu. Nous n\u2019avons pas d\u2019autres commentaires\u201d, a indiqu\u00e9 aux m\u00e9dias un porte-parole de l\u2019UEFA.<\/strong><\/p>\n<p><strong>La rencontre est programm\u00e9e jeudi \u00e0 21h00 (19h00 GMT) \u00e0 Lisbonne.<\/strong><\/p>\n<p><strong>Le club madril\u00e8ne a annonc\u00e9 dimanche que deux de ses membres, dont l\u2019identit\u00e9 n\u2019a pas \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9e, ont \u00e9t\u00e9 test\u00e9s positifs au Covid-19.<\/strong><\/p>\n<p><strong>Selon la m\u00eame source, l\u2019UEFA n\u2019a pas pr\u00e9cis\u00e9 s\u2019il s\u2019agissait de joueurs ou de membres de l\u2019encadrement.Selon l\u2019Atl\u00e9tico, apr\u00e8s des tests r\u00e9alis\u00e9s samedi, \u201cdeux cas positifs (\u2026) sont confin\u00e9s \u00e0 leur domicile respectif\u201d et leurs noms \u201cont imm\u00e9diatement \u00e9t\u00e9 communiqu\u00e9s aux autorit\u00e9s sanitaires espagnoles, portugaises, \u00e0 l\u2019UEFA, \u00e0 la F\u00e9d\u00e9ration espagnole, \u00e0 la F\u00e9d\u00e9ration portugaise et au Conseil sup\u00e9rieur des sports\u201d espagnol.<\/strong><\/p>\n<p><strong>Le club \u201ccolchonero\u201d devait conduire une nouvelle s\u00e9rie de tests aupr\u00e8s de ceux qui ont \u00e9t\u00e9 en contact avec les personnes contamin\u00e9es. L\u2019UEFA n\u2019a pas pr\u00e9cis\u00e9 quand ces r\u00e9sultats seraient connus.<\/strong><\/p>\n<p><strong>Interrompue par la pand\u00e9mie, la Ligue des champions, qui a repris vendredi et samedi avec les huiti\u00e8mes de finale retour qui n\u2019avaient pu \u00eatre disput\u00e9s avant le confinement, doit conna\u00eetre son d\u00e9nouement lors d\u2019un \u201cFinal 8\u201d in\u00e9dit et condens\u00e9, organis\u00e9 \u00e0 Lisbonne du 12 au 23 ao\u00fbt.<\/strong><\/p>\n<p><strong>Un protocole sanitaire de 33 pages a \u00e9t\u00e9 \u00e9dict\u00e9 par l\u2019UEFA pour encadrer ses comp\u00e9titions europ\u00e9ennes.<\/strong><\/p>\n<p><strong>Selon ce protocole, chaque \u00e9quipe doit fournir des r\u00e9sultats de tests avant de se rendre au Portugal, et sera de nouveau test\u00e9e \u00e0 la veille de sa premi\u00e8re rencontre. Chaque test positif imposera un isolement du joueur \u00e0 son h\u00f4tel.<\/strong><\/p>\n<p><strong>Pour pouvoir jouer, une \u00e9quipe devra disposer de 13 joueurs sains, y compris un gardien de but, selon une annexe du protocole.<\/strong><\/p>\n<p><strong>Si une \u00e9quipe ne dispose pas de 13 footballeurs figurant sur la \u201cliste A\u201d des joueurs \u00e9ligibles soumise au pr\u00e9alable, l\u2019UEFA \u201cpeut autoriser la reprogrammation du match\u201d.<\/strong><\/p>\n<p><strong>Si le match ne peut \u00eatre reprogramm\u00e9, l\u2019\u00e9quipe ne pouvant pas aligner 13 joueurs \u201csera tenue responsable\u201d et aura match perdu sur le score de 3 \u00e0 0, pr\u00e9voit encore l\u2019annexe.<\/strong><\/p>\n<p><strong>Alors que l\u2019UEFA mise sur un tournoi final \u00e0 marche forc\u00e9e entre le 12 et le 23 ao\u00fbt et esp\u00e8re r\u00e9ussir \u00e0 cr\u00e9er une bulle sanitaire dans la capitale portugaise, le timing de ces deux cas positifs \u00e0 l\u2019Atl\u00e9tico peut inqui\u00e9ter en vue d\u2019une fin de comp\u00e9tition ne laissant presque aucune marge de manoeuvre pour des reports \u00e9ventuels de rencontres.<\/strong><\/p>\n<p><strong>L\u2019instance europ\u00e9enne du football pourra toutefois esp\u00e9rer que l\u2019Atl\u00e9tico aura g\u00e9r\u00e9 son protocole sanitaire aussi bien que l\u2019avait fait le Real Madrid ces derniers jours. L\u2019attaquant du Real, Mariano Diaz, avait en effet \u00e9t\u00e9 test\u00e9 positif au Covid-19 avant le 8e de finale retour de C1 sur le terrain de Manchester City vendredi, mais ce cas \u00e9tait rest\u00e9 isol\u00e9 et n\u2019avait perturb\u00e9 en rien la tenue de la rencontre.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le12sport Le quart de finale de Ligue des champions entre Leipzig et l\u2019Atl\u00e9tico Madrid est \u201cprogramm\u00e9 comme pr\u00e9vu\u201d jeudi, a assur\u00e9 lundi l\u2019UEFA, au lendemain de l\u2019annonce de tests positifs au Covid-19 concernant deux membres du club espagnol. Le quart de finale entre Leipzig et l\u2019Atl\u00e9tico Madrid \u201cest programm\u00e9 comme pr\u00e9vu. Nous n\u2019avons pas d\u2019autres [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":1136,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[27],"tags":[],"yst_prominent_words":[526,3526,3524,140,1071,3523,2176,3528,3522,3527,3520,3518,276,1372,3132,3521,2294,3525,3519,338],"jetpack_featured_media_url":"https:\/\/le12.ma\/fr\/wp-content\/uploads\/2020\/08\/Capture-d\u2019e\u0301cran-2020-08-10-a\u0300-19.04.56.png","_links":{"self":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts\/1135"}],"collection":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/comments?post=1135"}],"version-history":[{"count":1,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts\/1135\/revisions"}],"predecessor-version":[{"id":1137,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/posts\/1135\/revisions\/1137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/media\/1136"}],"wp:attachment":[{"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/media?parent=1135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/categories?post=1135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/tags?post=1135"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/le12.ma\/fr\/wp-json\/wp\/v2\/yst_prominent_words?post=1135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}